{"id":11288,"date":"2023-04-13T23:05:05","date_gmt":"2023-04-14T03:05:05","guid":{"rendered":"https:\/\/victoriavynn.ca\/?product=victoria-vynn-gel-polish-no-332-insane-green"},"modified":"2026-08-11T08:55:02","modified_gmt":"2026-08-11T12:55:02","slug":"esmalte-en-gel-victoria-vynn-n-o-332-verde-alucinante","status":"publish","type":"product","link":"https:\/\/victoriavynn.ca\/es\/product\/victoria-vynn-gel-polish-no-332-insane-green\/","title":{"rendered":"Esmalte en gel Victoria VYNN n.\u00ba 332 Insane Green"},"content":{"rendered":"<p>El sistema de esmaltes en gel incluye esmaltes h\u00edbridos cl\u00e1sicos y duraderos que se curan en l\u00e1mparas UV y LED. El sistema cuenta con bases y capas de acabado con diferentes propiedades, durabilidad y acabados.<\/p>\n<p>Respondemos a las necesidades de nuestros clientes ofreci\u00e9ndoles una amplia variedad de colores con esmaltes h\u00edbridos de diferentes niveles de cobertura y efectos, en m\u00e1s de 200 tonos.<\/p>\n<p>Victoria VYNN Gel Polish Color es una l\u00ednea de esmaltes h\u00edbridos fotopolimerizables que se utiliza en dos tipos de aplicaciones: el sistema h\u00edbrido de 3 etapas y el sistema Soak Off de 4 etapas. Gel Polish Color destaca por la calidad de sus resultados y la versatilidad de sus aplicaciones: una sola paleta de colores, dos tipos de aplicaciones.<\/p>\n<p>Especificaciones del producto:<\/p>\n<ul>\n<li>Para uso en manicuras h\u00edbridas y \u00absoak off\u00bb.<\/li>\n<li>F\u00f3rmula de gel-esmalte.<\/li>\n<li>Dos capas finas proporcionan una cobertura perfecta y una gran intensidad de color.<\/li>\n<li>Se extiende de manera uniforme, sin rayas.<\/li>\n<li>Una amplia gama de colores: esmaltes, con purpurina, tonos pastel, ne\u00f3n, semitransparentes y colores para manicura francesa<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>El distribuidor l\u00edder en Canad\u00e1 de productos profesionales para el cuidado de las u\u00f1as. \u00a1Compra con confianza!<\/p>\n<p>Colecci\u00f3n: <a href=\"https:\/\/victoriavynn.ca\/es\/tags\/salon-gel-polish-crazy-in-colors-collection\/\">Esmalte en gel para sal\u00f3n \u00abCrazy in Colors\u00bb<\/a><\/p>","protected":false},"featured_media":73752,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[22],"product_cat":[29],"product_tag":[357,507],"class_list":["post-11288","product","type-product","status-publish","has-post-thumbnail","product_brand-victoria-vynn","product_cat-professional-nail-colours-gel","product_tag-salon-gel-polish-crazy-in-colors-collection","product_tag-spring-summer-gel-polish-colors","pa_size-8-ml","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product\/11288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/comments?post=11288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/media\/73752"}],"wp:attachment":[{"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/media?parent=11288"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product_brand?post=11288"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product_cat?post=11288"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product_tag?post=11288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}