{"id":4421,"date":"2022-09-02T18:52:26","date_gmt":"2022-09-02T22:52:26","guid":{"rendered":"https:\/\/victoriavynn.ca\/?product=coral-orange-gel-polish-020-coral-parrot"},"modified":"2026-07-29T09:31:38","modified_gmt":"2026-07-29T13:31:38","slug":"esmalte-en-gel-naranja-coral-020-coral-parrot","status":"publish","type":"product","link":"https:\/\/victoriavynn.ca\/es\/product\/coral-orange-gel-polish-020-coral-parrot\/","title":{"rendered":"Esmalte de gel h\u00edbrido cremoso puro n.\u00ba 020 Coral Parrot"},"content":{"rendered":"<p>El sistema Pure Creamy Hybrid est\u00e1 compuesto por esmaltes h\u00edbridos en gel cremosos que ofrecen una excelente cobertura y durabilidad. Es una f\u00f3rmula con un alto \u00edndice de seguridad, libre de olores irritantes y que se puede quitar con alcohol cosm\u00e9tico. El pincel corto y plano, dise\u00f1ado especialmente para la l\u00ednea de productos Pure, facilita una aplicaci\u00f3n uniforme. El sistema te permite crear manicuras h\u00edbridas ultrafinas. \u00a1Se cura \u00fanicamente en l\u00e1mparas LED!<\/p>\n<p>\u00a1Un maravilloso esmalte en gel naranja coral! El esmalte en gel h\u00edbrido cremoso de alta pigmentaci\u00f3n Victoria VYNN 020 Coral Parrot es una combinaci\u00f3n perfecta de naranja con un tono coral.<\/p>\n<p>\u00a1Los esmaltes h\u00edbridos Pure satisfacen las expectativas de las mujeres de todo el mundo! Creamos nuestras colecciones siguiendo las \u00faltimas tendencias, respondemos a las necesidades de nuestras clientas y resaltamos la belleza de sus manos.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Un maravilloso esmalte en gel naranja coral! El esmalte en gel h\u00edbrido cremoso de alta pigmentaci\u00f3n Victoria VYNN 020 Coral Parrot es una combinaci\u00f3n perfecta de naranja con un tono coral. El distribuidor l\u00edder en Canad\u00e1 de productos profesionales para u\u00f1as. \u00a1Compra con confianza!<\/p>","protected":false},"featured_media":72054,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[47],"product_tag":[251,517],"class_list":["post-4421","product","type-product","status-publish","has-post-thumbnail","product_cat-hybrid-gel-nail-colors","product_tag-pure-creamy-hybrid-gel-polish-colors","product_tag-spring-summer-vegan-creamy-colors","pa_size-8-ml","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product\/4421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/comments?post=4421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/media\/72054"}],"wp:attachment":[{"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/media?parent=4421"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product_brand?post=4421"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product_cat?post=4421"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/victoriavynn.ca\/es\/wp-json\/wp\/v2\/product_tag?post=4421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}