{"id":5077,"date":"2022-09-04T15:39:12","date_gmt":"2022-09-04T19:39:12","guid":{"rendered":"https:\/\/victoriavynn.ca\/?product=victoria-vynn-salon-gel-polish-color-no-307"},"modified":"2026-08-13T20:56:57","modified_gmt":"2026-08-14T00:56:57","slug":"vernis-gel-victoria-vynn-salon-couleur-n-307","status":"publish","type":"product","link":"https:\/\/victoriavynn.ca\/fr\/product\/victoria-vynn-salon-gel-polish-color-no-307\/","title":{"rendered":"Vernis gel de salon n\u00b0 307 Jaune Yuuga"},"content":{"rendered":"<p>Le syst\u00e8me Gel Polish comprend des vernis hybrides classiques et r\u00e9sistants, durcis sous des lampes UV et LED. Ce syst\u00e8me propose des bases et des top coats aux propri\u00e9t\u00e9s, \u00e0 la tenue et \u00e0 la finition vari\u00e9es. Nous r\u00e9pondons aux besoins de nos clientes en proposant une riche palette de couleurs avec des vernis hybrides offrant diff\u00e9rents niveaux de couvrance et d\u2019effets, dans plus de 200 teintes. Le jaune intense \u00ab Yellow Yuuga \u00bb, apr\u00e8s exposition \u00e0 la lumi\u00e8re du jour ou \u00e0 une source lumineuse artificielle, devient fluorescent et brille ainsi dans le noir. L\u2019intensit\u00e9 de cette luminescence d\u00e9pend de la dur\u00e9e d\u2019exposition du motif. Victoria VYNN Gel Polish Color est une gamme de vernis hybrides photopolym\u00e9risables, utilis\u00e9e dans deux types de techniques de pose : le syst\u00e8me hybride en 3 \u00e9tapes et le syst\u00e8me Soak Off en 4 \u00e9tapes. Gel Polish Color s\u00e9duit par la qualit\u00e9 de la pose et la diversit\u00e9 des applications possibles : une seule palette de couleurs, deux types de techniques de pose.<\/p>\n<p>Caract\u00e9ristiques techniques du produit :<\/p>\n<ul>\n<li>\u00c0 utiliser pour les manucures hybrides et \u00ab soak off \u00bb.<\/li>\n<li>Formule gel-vernis.<\/li>\n<li>Deux fines couches suffisent pour obtenir une couvrance parfaite et une couleur intense.<\/li>\n<li>Il s'\u00e9tale uniform\u00e9ment, sans laisser de traces.<\/li>\n<li>Une large gamme de couleurs : laques, paillettes, tons pastel, n\u00e9on, semi-transparentes et couleurs \u00ab French \u00bb.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Le \u00ab Yellow Yuuga \u00bb, d'un jaune intense, devient fluorescent apr\u00e8s avoir \u00e9t\u00e9 expos\u00e9 \u00e0 la lumi\u00e8re du jour ou \u00e0 une lumi\u00e8re artificielle, et brille donc dans le noir. L'intensit\u00e9 de cette luminescence d\u00e9pend de la dur\u00e9e d'exposition du motif.<\/p>\n<p>La gamme de vernis hybrides \u00ab Gel Polish Color \u00bb de Victoria VYNN, num\u00e9ro un des ventes au Canada, est une gamme de vernis hybrides photopolym\u00e9risables qui s'utilise selon deux techniques diff\u00e9rentes : le syst\u00e8me hybride en 3 \u00e9tapes et le syst\u00e8me \u00ab Soak Off \u00bb en 4 \u00e9tapes. La gamme \u00ab Gel Polish Color \u00bb s\u00e9duit par la qualit\u00e9 du r\u00e9sultat et la polyvalence de ses applications : une seule palette de couleurs, deux techniques diff\u00e9rentes.<\/p>","protected":false},"featured_media":72711,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[22],"product_cat":[29],"product_tag":[246,516],"class_list":["post-5077","product","type-product","status-publish","has-post-thumbnail","product_brand-victoria-vynn","product_cat-professional-nail-colours-gel","product_tag-gel-polish-colors","product_tag-glow-in-the-dark-gel-polishes","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/victoriavynn.ca\/fr\/wp-json\/wp\/v2\/product\/5077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/victoriavynn.ca\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/victoriavynn.ca\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/victoriavynn.ca\/fr\/wp-json\/wp\/v2\/comments?post=5077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/victoriavynn.ca\/fr\/wp-json\/wp\/v2\/media\/72711"}],"wp:attachment":[{"href":"https:\/\/victoriavynn.ca\/fr\/wp-json\/wp\/v2\/media?parent=5077"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/victoriavynn.ca\/fr\/wp-json\/wp\/v2\/product_brand?post=5077"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/victoriavynn.ca\/fr\/wp-json\/wp\/v2\/product_cat?post=5077"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/victoriavynn.ca\/fr\/wp-json\/wp\/v2\/product_tag?post=5077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}